{"id":10436,"date":"2023-10-30T19:58:38","date_gmt":"2023-10-30T19:58:38","guid":{"rendered":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/?post_type=product&#038;p=10436"},"modified":"2023-10-30T19:58:38","modified_gmt":"2023-10-30T19:58:38","slug":"cr-3361-tv-smart-tcl-rc902v-fmr2-sspt25-le-7689","status":"publish","type":"product","link":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/produto\/cr-3361-tv-smart-tcl-rc902v-fmr2-sspt25-le-7689\/","title":{"rendered":"CR-3361 &#8211; TV Smart TCL RC902V FMR2 SSPT25 &#8211; LE-7689"},"content":{"rendered":"<p>CR-3361 &#8211; TV Smart TCL RC902V FMR2 SSPT25 &#8211; LE-7689<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CR-3361 &#8211; TV Smart TCL RC902V FMR2 SSPT25 &#8211; LE-7689<\/p>\n","protected":false},"featured_media":10438,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11,210],"product_tag":[],"class_list":{"0":"post-10436","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paralelos","7":"product_cat-tcl","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product\/10436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/comments?post=10436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media\/10438"}],"wp:attachment":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media?parent=10436"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_brand?post=10436"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_cat?post=10436"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_tag?post=10436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}