{"id":1661,"date":"2015-05-22T14:58:08","date_gmt":"2015-05-22T14:58:08","guid":{"rendered":"http:\/\/www.casadocontroleremoto.com.br\/varejo\/?post_type=product&#038;p=1661"},"modified":"2018-07-03T15:24:41","modified_gmt":"2018-07-03T15:24:41","slug":"cr-1156","status":"publish","type":"product","link":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/produto\/cr-1156\/","title":{"rendered":"CR-1156 Receptor Parabolica  RP-500\/5006 MK-E322"},"content":{"rendered":"<p>RP-500\/5006 MK-E322<br \/>\nPara Receptor Parabolica<\/p>\n<p>RP-500\/5006<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RP-500\/5006 MK-E322<br \/>\nPara Receptor Parabolica<\/p>\n<p>RP-500\/5006<\/p>\n","protected":false},"featured_media":1662,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11,122],"product_tag":[],"class_list":{"0":"post-1661","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paralelos","7":"product_cat-plasmatic","9":"first","10":"outofstock","11":"shipping-taxable","12":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product\/1661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/comments?post=1661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media\/1662"}],"wp:attachment":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media?parent=1661"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_brand?post=1661"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_cat?post=1661"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_tag?post=1661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}