{"id":1922,"date":"2015-05-22T19:36:56","date_gmt":"2015-05-22T19:36:56","guid":{"rendered":"http:\/\/www.casadocontroleremoto.com.br\/varejo\/?post_type=product&#038;p=1922"},"modified":"2022-02-15T19:10:38","modified_gmt":"2022-02-15T19:10:38","slug":"cr-1434","status":"publish","type":"product","link":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/produto\/cr-1434\/","title":{"rendered":"CR-1434 TV TOSHIBA LUMINA  SS7180 LE-7180"},"content":{"rendered":"<p>MODELOS COMPAT\u00cdVEIS<\/p>\n<p>CT-7160<br \/>\nCT-7180<br \/>\nTVC-102<br \/>\nTodos os modelos Lumina Line<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SS7180<br \/>\nTV TOSHIBA LUMINA<\/p>\n<p>SS7180<\/p>\n","protected":false},"featured_media":1923,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11,101],"product_tag":[],"class_list":{"0":"post-1922","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paralelos","7":"product_cat-semp-toshiba","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product\/1922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/comments?post=1922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media\/1923"}],"wp:attachment":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media?parent=1922"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_brand?post=1922"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_cat?post=1922"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_tag?post=1922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}