{"id":2010,"date":"2015-05-25T12:10:55","date_gmt":"2015-05-25T12:10:55","guid":{"rendered":"http:\/\/www.casadocontroleremoto.com.br\/varejo\/?post_type=product&#038;p=2010"},"modified":"2018-07-03T15:23:31","modified_gmt":"2018-07-03T15:23:31","slug":"cr-1269","status":"publish","type":"product","link":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/produto\/cr-1269\/","title":{"rendered":"CR-1269 Receptor Parab\u00f3lica NET Jerrold  SKY 7941"},"content":{"rendered":"<p>SKY 7941<\/p>\n<p>Para Receptor Parab\u00f3lica NET Jerrold<\/p>\n<p>SKY 7941<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SKY 7941<\/p>\n<p>Para Receptor Parab\u00f3lica NET Jerrold<\/p>\n<p>SKY 7941<\/p>\n","protected":false},"featured_media":2011,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11,19],"product_tag":[],"class_list":{"0":"post-2010","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paralelos","7":"product_cat-receptores-digital","9":"first","10":"outofstock","11":"shipping-taxable","12":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product\/2010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/comments?post=2010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media\/2011"}],"wp:attachment":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media?parent=2010"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_brand?post=2010"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_cat?post=2010"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_tag?post=2010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}