{"id":9935,"date":"2020-12-21T11:11:47","date_gmt":"2020-12-21T11:11:47","guid":{"rendered":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/?post_type=product&#038;p=9935"},"modified":"2022-02-12T13:50:15","modified_gmt":"2022-02-12T13:50:15","slug":"cr-3247-ar-condicionado-samsung-max-plus-sky-9020-paralelo","status":"publish","type":"product","link":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/produto\/cr-3247-ar-condicionado-samsung-max-plus-sky-9020-paralelo\/","title":{"rendered":"CR-3247 &#8211; Ar Condicionado Samsung MAX Plus &#8211; SKY-9020 &#8211; Paralelo"},"content":{"rendered":"<p>CR-3247 &#8211; Ar Condicionado Samsung MAX Plus &#8211; SKY-9020 &#8211; Paralelo35<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CR-3247 &#8211; Ar Condicionado Samsung MAX Plus &#8211; SKY-9020 &#8211; Paralelo<\/p>\n","protected":false},"featured_media":9936,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11,99],"product_tag":[],"class_list":{"0":"post-9935","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paralelos","7":"product_cat-samsung","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product\/9935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/comments?post=9935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media\/9936"}],"wp:attachment":[{"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/media?parent=9935"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_brand?post=9935"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_cat?post=9935"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadocontroleremoto.com.br\/varejo\/wp-json\/wp\/v2\/product_tag?post=9935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}